{"id":86,"date":"2015-05-29T02:58:50","date_gmt":"2015-05-28T23:58:50","guid":{"rendered":"http:\/\/odysseus-contests.eu\/2016\/?page_id=86"},"modified":"2016-08-22T23:23:01","modified_gmt":"2016-08-22T20:23:01","slug":"calendar","status":"publish","type":"page","link":"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/","title":{"rendered":"Calendar"},"content":{"rendered":"<ul>\n<li>Opening of registrations: 1st September 2016<\/li>\n<li>Submissions deadline: 31st March 2017<\/li>\n<li>Regional phase: 30th April 2017 \u2013 30th June 2017<\/li>\n<li>Final phase &#8211; Award Ceremony: July 2017<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Opening of registrations: 1st September 2016 Submissions deadline: 31st March 2017 Regional phase: 30th April 2017 \u2013 30th June 2017 Final phase &#8211; Award Ceremony: July 2017<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20,"menu_order":30,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Calendar - ODYSSEUS II<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calendar - ODYSSEUS II\" \/>\n<meta property=\"og:description\" content=\"Opening of registrations: 1st September 2016 Submissions deadline: 31st March 2017 Regional phase: 30th April 2017 \u2013 30th June 2017 Final phase &#8211; Award Ceremony: July 2017\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/\" \/>\n<meta property=\"og:site_name\" content=\"ODYSSEUS II\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-22T20:23:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/\",\"name\":\"Calendar - ODYSSEUS II\",\"isPartOf\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\"},\"datePublished\":\"2015-05-28T23:58:50+00:00\",\"dateModified\":\"2016-08-22T20:23:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Explorers\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/explorers\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Calendar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/de\/\",\"name\":\"ODYSSEUS II\",\"description\":\"European Youth Space Contest\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calendar - ODYSSEUS II","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/","og_locale":"en_US","og_type":"article","og_title":"Calendar - ODYSSEUS II","og_description":"Opening of registrations: 1st September 2016 Submissions deadline: 31st March 2017 Regional phase: 30th April 2017 \u2013 30th June 2017 Final phase &#8211; Award Ceremony: July 2017","og_url":"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/","og_site_name":"ODYSSEUS II","article_modified_time":"2016-08-22T20:23:01+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/","url":"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/","name":"Calendar - ODYSSEUS II","isPartOf":{"@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website"},"datePublished":"2015-05-28T23:58:50+00:00","dateModified":"2016-08-22T20:23:01+00:00","breadcrumb":{"@id":"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/odysseus-contests.eu\/2016\/explorers\/calendar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseus-contests.eu\/2016\/"},{"@type":"ListItem","position":2,"name":"Explorers","item":"https:\/\/odysseus-contests.eu\/2016\/explorers\/"},{"@type":"ListItem","position":3,"name":"Calendar"}]},{"@type":"WebSite","@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website","url":"https:\/\/odysseus-contests.eu\/2016\/de\/","name":"ODYSSEUS II","description":"European Youth Space Contest","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/pages\/86"}],"collection":[{"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/comments?post=86"}],"version-history":[{"count":5,"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/pages\/86\/revisions"}],"predecessor-version":[{"id":13351,"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/pages\/86\/revisions\/13351"}],"up":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/pages\/20"}],"wp:attachment":[{"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/media?parent=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}