{"id":135,"date":"2015-05-29T03:25:54","date_gmt":"2015-05-29T00:25:54","guid":{"rendered":"http:\/\/odysseus-contests.eu\/2016\/?page_id=135"},"modified":"2015-07-01T19:27:54","modified_gmt":"2015-07-01T16:27:54","slug":"supporters","status":"publish","type":"page","link":"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/","title":{"rendered":"Supporters"},"content":{"rendered":"<p><a href=\"http:\/\/www.eaae-astronomy.org\" target=\"_blank\"><img decoding=\"async\" class=\"logoclass\" src=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/themes\/odysseus2\/img\/logos\/supporters_eaae.jpg\" \/><\/a><a href=\"https:\/\/cnes.fr\" target=\"_blank\"><img decoding=\"async\" class=\"logoclass\" src=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/themes\/odysseus2\/img\/logos\/supporters_cnes.jpg\" \/><\/a><a href=\"http:\/\/www.eurospace.org\" target=\"_blank\"><img decoding=\"async\" class=\"logoclass\" src=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/themes\/odysseus2\/img\/logos\/supporters_eurospace.jpg\" \/><\/a><a href=\"http:\/\/airbusdefenceandspace.com\" target=\"_blank\"><img decoding=\"async\" class=\"logoclass\" src=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/themes\/odysseus2\/img\/logos\/supporters_airbus.jpg\" \/><\/a><a href=\"https:\/\/www.thalesgroup.com\/en\/worldwide\/space\" target=\"_blank\"><img decoding=\"async\" class=\"logoclass\" src=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/themes\/odysseus2\/img\/logos\/supporters_thales.jpg\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":131,"menu_order":30,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Supporters - ODYSSEUS II<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Supporters - ODYSSEUS II\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/\" \/>\n<meta property=\"og:site_name\" content=\"ODYSSEUS II\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-01T16:27:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/themes\/odysseus2\/img\/logos\/supporters_eaae.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/\",\"name\":\"Supporters - ODYSSEUS II\",\"isPartOf\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\"},\"datePublished\":\"2015-05-29T00:25:54+00:00\",\"dateModified\":\"2015-07-01T16:27:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Odysseus II Project\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Supporters\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/de\/\",\"name\":\"ODYSSEUS II\",\"description\":\"European Youth Space Contest\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Supporters - ODYSSEUS II","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/","og_locale":"en_US","og_type":"article","og_title":"Supporters - ODYSSEUS II","og_url":"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/","og_site_name":"ODYSSEUS II","article_modified_time":"2015-07-01T16:27:54+00:00","og_image":[{"url":"http:\/\/odysseus-contests.eu\/2016\/wp-content\/themes\/odysseus2\/img\/logos\/supporters_eaae.jpg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/","url":"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/","name":"Supporters - ODYSSEUS II","isPartOf":{"@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website"},"datePublished":"2015-05-29T00:25:54+00:00","dateModified":"2015-07-01T16:27:54+00:00","breadcrumb":{"@id":"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/supporters\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseus-contests.eu\/2016\/"},{"@type":"ListItem","position":2,"name":"The Odysseus II Project","item":"https:\/\/odysseus-contests.eu\/2016\/odysseus-ii\/"},{"@type":"ListItem","position":3,"name":"Supporters"}]},{"@type":"WebSite","@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website","url":"https:\/\/odysseus-contests.eu\/2016\/de\/","name":"ODYSSEUS II","description":"European Youth Space Contest","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/pages\/135"}],"collection":[{"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/comments?post=135"}],"version-history":[{"count":0,"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/pages\/135\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/pages\/131"}],"wp:attachment":[{"href":"https:\/\/odysseus-contests.eu\/2016\/wp-json\/wp\/v2\/media?parent=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}