{"id":2013,"date":"2015-07-06T22:01:27","date_gmt":"2015-07-06T19:01:27","guid":{"rendered":"http:\/\/odysseus-contests.eu\/2016\/?page_id=2013"},"modified":"2016-01-26T18:16:49","modified_gmt":"2016-01-26T15:16:49","slug":"zonnestelsel-en-ruimtewetenschap","status":"publish","type":"page","link":"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/","title":{"rendered":"Zonnestelsel en ruimtewetenschap"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"img-responsive alignleft wp-image-274 size-full\" src=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/06\/content-resources-library-solar.jpg\" alt=\"content-resources-library-solar\" width=\"700\" height=\"400\" srcset=\"https:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/06\/content-resources-library-solar.jpg 700w, https:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/06\/content-resources-library-solar-300x171.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Exploration of the terrestrial<\/strong> planets \u2013 what can we learn for Earth;\n<ul>\n<li>Mars Exploration:\u00a0<a href=\"http:\/\/http:\/\/stem.org.uk\/rx8qb\">http:\/\/stem.org.uk\/rx8qb<\/a><\/li>\n<li>Mercury Exploration:\u00a0<a href=\"http:\/\/stem.org.uk\/rx4kn\">http:\/\/stem.org.uk\/rx4kn<\/a><\/li>\n<li>Venus Exploration:\u00a0<a href=\"http:\/\/stem.org.uk\/rx8qb\">http:\/\/stem.org.uk\/rx8qb<\/a><\/li>\n<\/ul>\n<\/li>\n<li>Big telescopes in space \u2013 why is space a good place to observe the sky?\n<ul>\n<li><a href=\"http:\/\/www.spacetelescope.org\/\">http:\/\/www.spacetelescope.org\/<\/a><\/li>\n<li><a href=\"http:\/\/hubblesite.org\/\">http:\/\/hubblesite.org\/<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Rocket systems<\/strong> why does a rocket fly and how;\n<ul>\n<li><a href=\"http:\/\/www.cnes-jeunes.fr\/web\/CNES-Jeunes-fr\/8136-quitter-la-terre.php\">http:\/\/www.cnes-jeunes.fr\/web\/CNES-Jeunes-fr\/8136-quitter-la-terre.php<\/a><\/li>\n<li><a href=\"http:\/\/www.esa.int\/esaKIDSen\/SEMYWIXJD1E_Technology_0.html\">http:\/\/www.esa.int\/esaKIDSen\/SEMYWIXJD1E_Technology_0.html<\/a><\/li>\n<\/ul>\n<\/li>\n<li>Manned space flight \u2013 how does a person feel several 1000 km from Earth?;\n<ul>\n<li><a href=\"http:\/\/www.asc-csa.gc.ca\/fra\/astronautes\/vivre.asp\">http:\/\/www.asc-csa.gc.ca\/fra\/astronautes\/vivre.asp<\/a><\/li>\n<li><a href=\"http:\/\/www.esa.int\/esaKIDSfr\/SEMRYS9TVPG_LifeinSpace_0.html\">http:\/\/www.esa.int\/esaKIDSfr\/SEMRYS9TVPG_LifeinSpace_0.html<\/a><\/li>\n<\/ul>\n<\/li>\n<li>Concept of a permanent lunar city \u2013 how to survive on the Moon?;\n<ul>\n<li><a href=\"http:\/\/www.esa.int\/fre\/ESA_in_your_country\/France\/Construire_une_base_lunaire_en_impression_3D\">http:\/\/www.esa.int\/fre\/ESA_in_your_country\/France\/Construire_une_base_lunaire_en_impression_3D<\/a><\/li>\n<li><a href=\"http:\/\/www.esa.int\/esaKIDSfr\/SEMPMWWJD1E_OurUniverse_0.html\">http:\/\/www.esa.int\/esaKIDSfr\/SEMPMWWJD1E_OurUniverse_0.html<\/a><\/li>\n<\/ul>\n<\/li>\n<li>How does Earth look from the surface of the Moon and the surface of Venus (drawings);\n<ul>\n<li><a href=\"http:\/\/cnes.photonpro.net\/cnes\/category\/137\">http:\/\/cnes.photonpro.net\/cnes\/category\/137<\/a><\/li>\n<\/ul>\n<\/li>\n<li>Big telescopes in space \u2013 why is space a good place to observe the sky?\n<ul>\n<li><a href=\"http:\/\/www.herschel.fr\/\">http:\/\/www.herschel.fr\/<\/a><\/li>\n<li><a href=\"https:\/\/jeunes.cnes.fr\/fr\/web\/CNES-Jeunes-fr\/9695-herschel-un-telescope-revele-l-univers-invisible.php\">https:\/\/jeunes.cnes.fr\/fr\/web\/CNES-Jeunes-fr\/9695-herschel-un-telescope-revele-l-univers-invisible.php<\/a><\/li>\n<li><a href=\"http:\/\/www.asc-csa.gc.ca\/fra\/satellites\/jwst\/\">http:\/\/www.asc-csa.gc.ca\/fra\/satellites\/jwst\/<\/a><\/li>\n<li><a href=\"http:\/\/www.insu.cnrs.fr\/univers\/le-syst-me-solaire\/spitzer-d-tecte-une-vari-t-d-ast-ro-des-plus-riche-qu-attendue\">http:\/\/www.insu.cnrs.fr\/univers\/le-syst-me-solaire\/spitzer-d-tecte-une-vari-t-d-ast-ro-des-plus-riche-qu-attendue<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Exploration of the terrestrial<\/strong> planets \u2013 what can we learn for Earth;\n<ul>\n<li>Mars Exploration:\u00a0<a href=\"http:\/\/www.asi.it\/it\/attivita\/esplorazione-del-sistema-solare\/mars-express\">http:\/\/www.asi.it\/it\/attivita\/esplorazione-del-sistema-solare\/mars-express<\/a><\/li>\n<li>Mercury Exploration:\u00a0<a href=\"http:\/\/www.asi.it\/it\/attivita\/esplorazione-del-sistema-solare\/bepi-colombo\">http:\/\/www.asi.it\/it\/attivita\/esplorazione-del-sistema-solare\/bepi-colombo<\/a><\/li>\n<li>Venus Exploration:\u00a0<a href=\"http:\/\/www.asi.it\/it\/attivita\/esplorazione-del-sistema-solare\/venus-express\">http:\/\/www.asi.it\/it\/attivita\/esplorazione-del-sistema-solare\/venus-express<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Links in other languages<\/p>\n<ul>\n<li><a href=\"http:\/\/odysseus-contests.eu\/2016\/?p=185\" target=\"_blank\">English<\/a><\/li>\n<li><a href=\"http:\/\/odysseus-contests.eu\/2016\/da\/profile\/\" target=\"_blank\">German<\/a><\/li>\n<li><a href=\"http:\/\/odysseus-contests.eu\/2016\/?p=1359\" target=\"_blank\">French<\/a><\/li>\n<li><a href=\"http:\/\/odysseus-contests.eu\/2016\/?p=3776\" target=\"_blank\">Spanish<\/a><\/li>\n<li><a href=\"http:\/\/odysseus-contests.eu\/2016\/?p=2120\" target=\"_blank\">Italian<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Exploration of the terrestrial planets \u2013 what can we learn for Earth; Mars Exploration:\u00a0http:\/\/stem.org.uk\/rx8qb Mercury Exploration:\u00a0http:\/\/stem.org.uk\/rx4kn Venus Exploration:\u00a0http:\/\/stem.org.uk\/rx8qb Big telescopes in space \u2013 why is space a good place to observe the sky? http:\/\/www.spacetelescope.org\/ http:\/\/hubblesite.org\/ &nbsp; Rocket systems why does a rocket fly and how; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1940,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zonnestelsel en ruimtewetenschap - ODYSSEUS II<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zonnestelsel en ruimtewetenschap - ODYSSEUS II\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Exploration of the terrestrial planets \u2013 what can we learn for Earth; Mars Exploration:\u00a0http:\/\/stem.org.uk\/rx8qb Mercury Exploration:\u00a0http:\/\/stem.org.uk\/rx4kn Venus Exploration:\u00a0http:\/\/stem.org.uk\/rx8qb Big telescopes in space \u2013 why is space a good place to observe the sky? http:\/\/www.spacetelescope.org\/ http:\/\/hubblesite.org\/ &nbsp; Rocket systems why does a rocket fly and how; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/\" \/>\n<meta property=\"og:site_name\" content=\"ODYSSEUS II\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-26T15:16:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/06\/content-resources-library-solar.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/\",\"name\":\"Zonnestelsel en ruimtewetenschap - ODYSSEUS II\",\"isPartOf\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\"},\"datePublished\":\"2015-07-06T19:01:27+00:00\",\"dateModified\":\"2016-01-26T15:16:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/#breadcrumb\"},\"inLanguage\":\"nl\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bibliotheek\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zonnestelsel en ruimtewetenschap\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/de\/\",\"name\":\"ODYSSEUS II\",\"description\":\"European Youth Space Contest\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zonnestelsel en ruimtewetenschap - ODYSSEUS II","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/","og_locale":"nl_NL","og_type":"article","og_title":"Zonnestelsel en ruimtewetenschap - ODYSSEUS II","og_description":"&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Exploration of the terrestrial planets \u2013 what can we learn for Earth; Mars Exploration:\u00a0http:\/\/stem.org.uk\/rx8qb Mercury Exploration:\u00a0http:\/\/stem.org.uk\/rx4kn Venus Exploration:\u00a0http:\/\/stem.org.uk\/rx8qb Big telescopes in space \u2013 why is space a good place to observe the sky? http:\/\/www.spacetelescope.org\/ http:\/\/hubblesite.org\/ &nbsp; Rocket systems why does a rocket fly and how; [&hellip;]","og_url":"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/","og_site_name":"ODYSSEUS II","article_modified_time":"2016-01-26T15:16:49+00:00","og_image":[{"url":"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/06\/content-resources-library-solar.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/","url":"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/","name":"Zonnestelsel en ruimtewetenschap - ODYSSEUS II","isPartOf":{"@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website"},"datePublished":"2015-07-06T19:01:27+00:00","dateModified":"2016-01-26T15:16:49+00:00","breadcrumb":{"@id":"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/#breadcrumb"},"inLanguage":"nl","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/zonnestelsel-en-ruimtewetenschap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseus-contests.eu\/2016\/nl\/"},{"@type":"ListItem","position":2,"name":"Bibliotheek","item":"https:\/\/odysseus-contests.eu\/2016\/nl\/bibliotheek\/"},{"@type":"ListItem","position":3,"name":"Zonnestelsel en ruimtewetenschap"}]},{"@type":"WebSite","@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website","url":"https:\/\/odysseus-contests.eu\/2016\/de\/","name":"ODYSSEUS II","description":"European Youth Space Contest","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl"}]}},"_links":{"self":[{"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/pages\/2013"}],"collection":[{"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/comments?post=2013"}],"version-history":[{"count":1,"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/pages\/2013\/revisions"}],"predecessor-version":[{"id":7373,"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/pages\/2013\/revisions\/7373"}],"up":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/pages\/1940"}],"wp:attachment":[{"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/media?parent=2013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}