{"id":1907,"date":"2015-07-06T21:11:11","date_gmt":"2015-07-06T18:11:11","guid":{"rendered":"http:\/\/odysseus-contests.eu\/2016\/?page_id=1907"},"modified":"2015-09-27T14:47:05","modified_gmt":"2015-09-27T11:47:05","slug":"media-resources","status":"publish","type":"page","link":"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/","title":{"rendered":"Mediahulpmiddelen"},"content":{"rendered":"<h3><b>Odysseus II Logo\u2019s<\/b><\/h3>\n<p>Klik <u><a href=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/odysseus_logos.zip\">hier<\/a><\/u> om het Odysseus II logo in .jpg en .eps formaat te downloaden.<\/p>\n<h3>Odysseus II Trailer<\/h3>\n<p><em>Teaser Video 720p\u00a0<\/em><a href=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/odysseus_720p.mp4\">odysseus_720p<\/a><\/p>\n<h3>Odysseus II Leaflet (EN)<\/h3>\n<p><a href=\"http:\/\/iframewidth=650height=470src=\/\/e.issuu.com\/embed.html#16787370\/15293599frameborder=0allowfullscreen\/iframe\"><iframe loading=\"lazy\" src=\"\/\/e.issuu.com\/embed.html#16787370\/15293599\" width=\"650\" height=\"470\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/a><\/p>\n<p>Download the Leaflet <a href=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/ODYSSEUS_Leafet_issuu.pdf\">here<\/a><\/p>\n<h3>Odysseus II Poster<\/h3>\n<p><a href=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/POSTER_A3_RGB1.jpg\" target=\"_blank\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-5934 size-thumbnail\" title=\"Poster_A3\" src=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/POSTER_A3_RGB1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>Download the Poster in A3 size in .pdf format <a href=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/POSTER_ODYSSEUS_A3_RGB.pdf\" target=\"_blank\">here<\/a><\/p>\n<p><a href=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/POSTER_A4_RGB1.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-thumbnail wp-image-5948\" src=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/POSTER_A4_RGB1-150x150.jpg\" alt=\"POSTER_A4_RGB_OUTLINED TEXTS\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>Download the Poster in A4 size and in .pdf format <a href=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/POSTER_ODYSSEUS_A4_RGB.pdf\" target=\"_blank\">here<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Odysseus II Logo\u2019s Klik hier om het Odysseus II logo in .jpg en .eps formaat te downloaden. Odysseus II Trailer Teaser Video 720p\u00a0odysseus_720p Odysseus II Leaflet (EN) Download the Leaflet here Odysseus II Poster Download the Poster in A3 size in .pdf format here Download the Poster in A4 size and in .pdf format here<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1901,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mediahulpmiddelen - ODYSSEUS II<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mediahulpmiddelen - ODYSSEUS II\" \/>\n<meta property=\"og:description\" content=\"Odysseus II Logo\u2019s Klik hier om het Odysseus II logo in .jpg en .eps formaat te downloaden. Odysseus II Trailer Teaser Video 720p\u00a0odysseus_720p Odysseus II Leaflet (EN) Download the Leaflet here Odysseus II Poster Download the Poster in A3 size in .pdf format here Download the Poster in A4 size and in .pdf format here\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/\" \/>\n<meta property=\"og:site_name\" content=\"ODYSSEUS II\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-27T11:47:05+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/POSTER_A3_RGB1-150x150.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/\",\"name\":\"Mediahulpmiddelen - ODYSSEUS II\",\"isPartOf\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\"},\"datePublished\":\"2015-07-06T18:11:11+00:00\",\"dateModified\":\"2015-09-27T11:47:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/#breadcrumb\"},\"inLanguage\":\"nl\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Media\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mediahulpmiddelen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/de\/\",\"name\":\"ODYSSEUS II\",\"description\":\"European Youth Space Contest\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mediahulpmiddelen - ODYSSEUS II","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/","og_locale":"nl_NL","og_type":"article","og_title":"Mediahulpmiddelen - ODYSSEUS II","og_description":"Odysseus II Logo\u2019s Klik hier om het Odysseus II logo in .jpg en .eps formaat te downloaden. Odysseus II Trailer Teaser Video 720p\u00a0odysseus_720p Odysseus II Leaflet (EN) Download the Leaflet here Odysseus II Poster Download the Poster in A3 size in .pdf format here Download the Poster in A4 size and in .pdf format here","og_url":"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/","og_site_name":"ODYSSEUS II","article_modified_time":"2015-09-27T11:47:05+00:00","og_image":[{"url":"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/POSTER_A3_RGB1-150x150.jpg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/","url":"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/","name":"Mediahulpmiddelen - ODYSSEUS II","isPartOf":{"@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website"},"datePublished":"2015-07-06T18:11:11+00:00","dateModified":"2015-09-27T11:47:05+00:00","breadcrumb":{"@id":"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/#breadcrumb"},"inLanguage":"nl","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/media-resources\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseus-contests.eu\/2016\/nl\/"},{"@type":"ListItem","position":2,"name":"Media","item":"https:\/\/odysseus-contests.eu\/2016\/nl\/media-3\/"},{"@type":"ListItem","position":3,"name":"Mediahulpmiddelen"}]},{"@type":"WebSite","@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website","url":"https:\/\/odysseus-contests.eu\/2016\/de\/","name":"ODYSSEUS II","description":"European Youth Space Contest","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl"}]}},"_links":{"self":[{"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/pages\/1907"}],"collection":[{"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/comments?post=1907"}],"version-history":[{"count":0,"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/pages\/1907\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/pages\/1901"}],"wp:attachment":[{"href":"https:\/\/odysseus-contests.eu\/2016\/nl\/wp-json\/wp\/v2\/media?parent=1907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}