{"id":2206,"date":"2015-07-07T01:43:29","date_gmt":"2015-07-06T22:43:29","guid":{"rendered":"http:\/\/odysseus-contests.eu\/2016\/?page_id=2206"},"modified":"2015-07-11T21:53:26","modified_gmt":"2015-07-11T18:53:26","slug":"prizes","status":"publish","type":"page","link":"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/","title":{"rendered":"Premi"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"img-responsive alignleft wp-image-337 size-full\" src=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/content-prizes-skywalkers1.jpg\" alt=\"content-prizes-skywalkers\" width=\"700\" height=\"400\" srcset=\"https:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/content-prizes-skywalkers1.jpg 700w, https:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/content-prizes-skywalkers1-300x171.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>Tutti e tre i vincitori a livello nazionale nelle categorie Junior Skywalkers e Senior Skywalkers avranno le loro immagini esposte nella Winners\u2019 Gallery. Come premio riceveranno una medaglia e il kit di montaggio del modello di un razzo che sar\u00e0 spedito direttamente alla scuola (o a casa) dagli organizzatori del concorso.<\/p>\n<p>I vincitori a livello internazionale del concorso riceveranno un iPad Air 2, con inclusi e-booked applicazioni di soggetto spaziale, oltre al diploma di \u201cEuropean Youth Space Ambassador\u201d, inviati direttamente alla scuola (o a casa).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tutti e tre i vincitori a livello nazionale nelle categorie Junior Skywalkers e Senior Skywalkers avranno le loro immagini esposte nella Winners\u2019 Gallery. Come premio riceveranno una medaglia e il kit di montaggio del modello di un razzo che sar\u00e0 spedito direttamente alla scuola (o a casa) dagli organizzatori del concorso. I vincitori a livello [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2283,"menu_order":40,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Premi - ODYSSEUS II<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premi - ODYSSEUS II\" \/>\n<meta property=\"og:description\" content=\"Tutti e tre i vincitori a livello nazionale nelle categorie Junior Skywalkers e Senior Skywalkers avranno le loro immagini esposte nella Winners\u2019 Gallery. Come premio riceveranno una medaglia e il kit di montaggio del modello di un razzo che sar\u00e0 spedito direttamente alla scuola (o a casa) dagli organizzatori del concorso. I vincitori a livello [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/\" \/>\n<meta property=\"og:site_name\" content=\"ODYSSEUS II\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-11T18:53:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/content-prizes-skywalkers1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/\",\"name\":\"Premi - ODYSSEUS II\",\"isPartOf\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\"},\"datePublished\":\"2015-07-06T22:43:29+00:00\",\"dateModified\":\"2015-07-11T18:53:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Skywalkers\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Premi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/de\/\",\"name\":\"ODYSSEUS II\",\"description\":\"European Youth Space Contest\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premi - ODYSSEUS II","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/","og_locale":"it_IT","og_type":"article","og_title":"Premi - ODYSSEUS II","og_description":"Tutti e tre i vincitori a livello nazionale nelle categorie Junior Skywalkers e Senior Skywalkers avranno le loro immagini esposte nella Winners\u2019 Gallery. Come premio riceveranno una medaglia e il kit di montaggio del modello di un razzo che sar\u00e0 spedito direttamente alla scuola (o a casa) dagli organizzatori del concorso. I vincitori a livello [&hellip;]","og_url":"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/","og_site_name":"ODYSSEUS II","article_modified_time":"2015-07-11T18:53:26+00:00","og_image":[{"url":"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/content-prizes-skywalkers1.jpg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/","url":"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/","name":"Premi - ODYSSEUS II","isPartOf":{"@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website"},"datePublished":"2015-07-06T22:43:29+00:00","dateModified":"2015-07-11T18:53:26+00:00","breadcrumb":{"@id":"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/prizes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseus-contests.eu\/2016\/it\/"},{"@type":"ListItem","position":2,"name":"Skywalkers","item":"https:\/\/odysseus-contests.eu\/2016\/it\/skywalkers-5\/"},{"@type":"ListItem","position":3,"name":"Premi"}]},{"@type":"WebSite","@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website","url":"https:\/\/odysseus-contests.eu\/2016\/de\/","name":"ODYSSEUS II","description":"European Youth Space Contest","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/odysseus-contests.eu\/2016\/it\/wp-json\/wp\/v2\/pages\/2206"}],"collection":[{"href":"https:\/\/odysseus-contests.eu\/2016\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odysseus-contests.eu\/2016\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/it\/wp-json\/wp\/v2\/comments?post=2206"}],"version-history":[{"count":0,"href":"https:\/\/odysseus-contests.eu\/2016\/it\/wp-json\/wp\/v2\/pages\/2206\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/it\/wp-json\/wp\/v2\/pages\/2283"}],"wp:attachment":[{"href":"https:\/\/odysseus-contests.eu\/2016\/it\/wp-json\/wp\/v2\/media?parent=2206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}