{"id":1372,"date":"2015-06-30T22:53:41","date_gmt":"2015-06-30T19:53:41","guid":{"rendered":"http:\/\/odysseus-contests.eu\/2016\/?page_id=1372"},"modified":"2015-06-30T22:53:41","modified_gmt":"2015-06-30T19:53:41","slug":"copernicus-earth-observations","status":"publish","type":"page","link":"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/","title":{"rendered":"Copernicus : Observations de la Terre"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"img-responsive alignleft wp-image-293 size-full\" src=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/06\/content-resources-library-coprnicus.jpg\" alt=\"content-resources-library-coprnicus\" width=\"700\" height=\"400\" srcset=\"https:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/06\/content-resources-library-coprnicus.jpg 700w, https:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/06\/content-resources-library-coprnicus-300x171.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><em>Prochainement<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prochainement<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1308,"menu_order":60,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Copernicus : Observations de la Terre - ODYSSEUS II<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Copernicus : Observations de la Terre - ODYSSEUS II\" \/>\n<meta property=\"og:description\" content=\"Prochainement\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/\" \/>\n<meta property=\"og:site_name\" content=\"ODYSSEUS II\" \/>\n<meta property=\"og:image\" content=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/06\/content-resources-library-coprnicus.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/\",\"name\":\"Copernicus : Observations de la Terre - ODYSSEUS II\",\"isPartOf\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\"},\"datePublished\":\"2015-06-30T19:53:41+00:00\",\"dateModified\":\"2015-06-30T19:53:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biblioth\u00e8que\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Copernicus : Observations de la Terre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/de\/\",\"name\":\"ODYSSEUS II\",\"description\":\"Concours spatial des jeunes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Copernicus : Observations de la Terre - ODYSSEUS II","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/","og_locale":"fr_FR","og_type":"article","og_title":"Copernicus : Observations de la Terre - ODYSSEUS II","og_description":"Prochainement","og_url":"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/","og_site_name":"ODYSSEUS II","og_image":[{"url":"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/06\/content-resources-library-coprnicus.jpg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/","url":"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/","name":"Copernicus : Observations de la Terre - ODYSSEUS II","isPartOf":{"@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website"},"datePublished":"2015-06-30T19:53:41+00:00","dateModified":"2015-06-30T19:53:41+00:00","breadcrumb":{"@id":"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/copernicus-earth-observations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseus-contests.eu\/2016\/fr\/"},{"@type":"ListItem","position":2,"name":"Biblioth\u00e8que","item":"https:\/\/odysseus-contests.eu\/2016\/fr\/bibliotheque\/"},{"@type":"ListItem","position":3,"name":"Copernicus : Observations de la Terre"}]},{"@type":"WebSite","@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website","url":"https:\/\/odysseus-contests.eu\/2016\/de\/","name":"ODYSSEUS II","description":"Concours spatial des jeunes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/pages\/1372"}],"collection":[{"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/comments?post=1372"}],"version-history":[{"count":0,"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/pages\/1372\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/pages\/1308"}],"wp:attachment":[{"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/media?parent=1372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}