{"id":1274,"date":"2015-06-30T21:28:36","date_gmt":"2015-06-30T18:28:36","guid":{"rendered":"http:\/\/odysseus-contests.eu\/2016\/?page_id=1274"},"modified":"2015-06-30T21:28:36","modified_gmt":"2015-06-30T18:28:36","slug":"communiques-de-presse","status":"publish","type":"page","link":"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/","title":{"rendered":"Communiqu\u00e9s de Presse"},"content":{"rendered":"<p><em>Prochainement<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prochainement<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1270,"menu_order":20,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Communiqu\u00e9s de Presse - ODYSSEUS II<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Communiqu\u00e9s de Presse - ODYSSEUS II\" \/>\n<meta property=\"og:description\" content=\"Prochainement\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/\" \/>\n<meta property=\"og:site_name\" content=\"ODYSSEUS II\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/\",\"name\":\"Communiqu\u00e9s de Presse - ODYSSEUS II\",\"isPartOf\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\"},\"datePublished\":\"2015-06-30T18:28:36+00:00\",\"dateModified\":\"2015-06-30T18:28:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9dias\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Communiqu\u00e9s de Presse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/de\/\",\"name\":\"ODYSSEUS II\",\"description\":\"Concours spatial des jeunes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Communiqu\u00e9s de Presse - ODYSSEUS II","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/","og_locale":"fr_FR","og_type":"article","og_title":"Communiqu\u00e9s de Presse - ODYSSEUS II","og_description":"Prochainement","og_url":"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/","og_site_name":"ODYSSEUS II","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/","url":"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/","name":"Communiqu\u00e9s de Presse - ODYSSEUS II","isPartOf":{"@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website"},"datePublished":"2015-06-30T18:28:36+00:00","dateModified":"2015-06-30T18:28:36+00:00","breadcrumb":{"@id":"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/communiques-de-presse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseus-contests.eu\/2016\/fr\/"},{"@type":"ListItem","position":2,"name":"M\u00e9dias","item":"https:\/\/odysseus-contests.eu\/2016\/fr\/media\/"},{"@type":"ListItem","position":3,"name":"Communiqu\u00e9s de Presse"}]},{"@type":"WebSite","@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website","url":"https:\/\/odysseus-contests.eu\/2016\/de\/","name":"ODYSSEUS II","description":"Concours spatial des jeunes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/pages\/1274"}],"collection":[{"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/comments?post=1274"}],"version-history":[{"count":0,"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/pages\/1274\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/pages\/1270"}],"wp:attachment":[{"href":"https:\/\/odysseus-contests.eu\/2016\/fr\/wp-json\/wp\/v2\/media?parent=1274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}