{"id":3902,"date":"2015-08-14T23:22:40","date_gmt":"2015-08-14T20:22:40","guid":{"rendered":"http:\/\/odysseus-contests.eu\/2016\/?page_id=3902"},"modified":"2015-08-14T23:22:40","modified_gmt":"2015-08-14T20:22:40","slug":"categoria-pioneers","status":"publish","type":"page","link":"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/","title":{"rendered":"Categor\u00eda Pioneers"},"content":{"rendered":"<h4>Primer premio:<\/h4>\n<ul>\n<li>Viaje al Centro de Espacial de Kourou en Guayana (<strong><em>Centre Spatial Guyanais<\/em><\/strong> o <strong><em>CSG)<\/em><\/strong>. Incluye: Billetes de avi\u00f3n, alojamiento, comidas, seguro, participaci\u00f3n en eventos, visitas y tours guiados al Centro Espacial y otras atracciones para todos los miembros del equipo y su tutor.<\/li>\n<li>Diploma \u201c<em>Joven Embajador Europeo del Espacio<\/em>\u201d.<\/li>\n<\/ul>\n<h4>Premio a los ganadores regionaless:<\/h4>\n<ul>\n<li>Un telescopio de alta gama (Celestron Nexstar o similar) para cada miembro del equipo de los diez equipos finalistas \u2013los ganadores de las semifinales regionales-.<\/li>\n<\/ul>\n<ul>\n<li>Viaje a la ciudad donde se celebr\u00e9 la Final Internacional. Incluye: gastos de viaje, alojamiento, comidas, seguro, visitas y participaci\u00f3n en actividades para todos los miembros del equipo y sus tutores.<\/li>\n<\/ul>\n<h4>Ganadores nacionales:<\/h4>\n<ul>\n<li>Viaje a la ciudad donde se celebren las Finales Regionales. Incluye: gastos de viaje, alojamiento, comidas, seguro, visitas y participaci\u00f3n en eventos para todos los miembros del equipo y sus tutores.<\/li>\n<\/ul>\n<ul>\n<li>Un pack de recuerdo del concurso Odysseus II<\/li>\n<li>Medalla conmemorativa de ganador.<\/li>\n<\/ul>\n<p>Todos los participantes recibir\u00e1n un certificado de participaci\u00f3n en el Concurso Odysseus II.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primer premio: Viaje al Centro de Espacial de Kourou en Guayana (Centre Spatial Guyanais o CSG). Incluye: Billetes de avi\u00f3n, alojamiento, comidas, seguro, participaci\u00f3n en eventos, visitas y tours guiados al Centro Espacial y otras atracciones para todos los miembros del equipo y su tutor. Diploma \u201cJoven Embajador Europeo del Espacio\u201d. Premio a los ganadores [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1142,"parent":3891,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Categor\u00eda Pioneers - ODYSSEUS II<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Categor\u00eda Pioneers - ODYSSEUS II\" \/>\n<meta property=\"og:description\" content=\"Primer premio: Viaje al Centro de Espacial de Kourou en Guayana (Centre Spatial Guyanais o CSG). Incluye: Billetes de avi\u00f3n, alojamiento, comidas, seguro, participaci\u00f3n en eventos, visitas y tours guiados al Centro Espacial y otras atracciones para todos los miembros del equipo y su tutor. Diploma \u201cJoven Embajador Europeo del Espacio\u201d. Premio a los ganadores [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/\" \/>\n<meta property=\"og:site_name\" content=\"ODYSSEUS II\" \/>\n<meta property=\"og:image\" content=\"https:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/about-prizes-pioneers-main.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/\",\"name\":\"Categor\u00eda Pioneers - ODYSSEUS II\",\"isPartOf\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\"},\"datePublished\":\"2015-08-14T20:22:40+00:00\",\"dateModified\":\"2015-08-14T20:22:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premios\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Categor\u00eda Pioneers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/de\/\",\"name\":\"ODYSSEUS II\",\"description\":\"European Youth Space Contest\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Categor\u00eda Pioneers - ODYSSEUS II","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/","og_locale":"es_ES","og_type":"article","og_title":"Categor\u00eda Pioneers - ODYSSEUS II","og_description":"Primer premio: Viaje al Centro de Espacial de Kourou en Guayana (Centre Spatial Guyanais o CSG). Incluye: Billetes de avi\u00f3n, alojamiento, comidas, seguro, participaci\u00f3n en eventos, visitas y tours guiados al Centro Espacial y otras atracciones para todos los miembros del equipo y su tutor. Diploma \u201cJoven Embajador Europeo del Espacio\u201d. Premio a los ganadores [&hellip;]","og_url":"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/","og_site_name":"ODYSSEUS II","og_image":[{"width":1920,"height":666,"url":"https:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/about-prizes-pioneers-main.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/","url":"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/","name":"Categor\u00eda Pioneers - ODYSSEUS II","isPartOf":{"@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website"},"datePublished":"2015-08-14T20:22:40+00:00","dateModified":"2015-08-14T20:22:40+00:00","breadcrumb":{"@id":"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/categoria-pioneers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseus-contests.eu\/2016\/es\/"},{"@type":"ListItem","position":2,"name":"Premios","item":"https:\/\/odysseus-contests.eu\/2016\/es\/premios\/"},{"@type":"ListItem","position":3,"name":"Categor\u00eda Pioneers"}]},{"@type":"WebSite","@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website","url":"https:\/\/odysseus-contests.eu\/2016\/de\/","name":"ODYSSEUS II","description":"European Youth Space Contest","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/odysseus-contests.eu\/2016\/es\/wp-json\/wp\/v2\/pages\/3902"}],"collection":[{"href":"https:\/\/odysseus-contests.eu\/2016\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odysseus-contests.eu\/2016\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/es\/wp-json\/wp\/v2\/comments?post=3902"}],"version-history":[{"count":0,"href":"https:\/\/odysseus-contests.eu\/2016\/es\/wp-json\/wp\/v2\/pages\/3902\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/es\/wp-json\/wp\/v2\/pages\/3891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/es\/wp-json\/wp\/v2\/media\/1142"}],"wp:attachment":[{"href":"https:\/\/odysseus-contests.eu\/2016\/es\/wp-json\/wp\/v2\/media?parent=3902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}