{"id":536,"date":"2015-06-18T21:03:07","date_gmt":"2015-06-18T18:03:07","guid":{"rendered":"http:\/\/odysseus-contests.eu\/2016\/?page_id=536"},"modified":"2015-06-18T21:03:07","modified_gmt":"2015-06-18T18:03:07","slug":"indsendte-bidrag","status":"publish","type":"page","link":"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/","title":{"rendered":"Indsendte bidrag"},"content":{"rendered":"<p><em>Alle bidrag bliver vist p\u00e5 Odysseus-hjemmesiden efter udl\u00f8b af frist for indsendelse af bidrag (januar 2016).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alle bidrag bliver vist p\u00e5 Odysseus-hjemmesiden efter udl\u00f8b af frist for indsendelse af bidrag (januar 2016).<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":517,"menu_order":60,"comment_status":"closed","ping_status":"closed","template":"template_projects_explorers.php","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Indsendte bidrag - ODYSSEUS II<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/\" \/>\n<meta property=\"og:locale\" content=\"da_DK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indsendte bidrag - ODYSSEUS II\" \/>\n<meta property=\"og:description\" content=\"Alle bidrag bliver vist p\u00e5 Odysseus-hjemmesiden efter udl\u00f8b af frist for indsendelse af bidrag (januar 2016).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/\" \/>\n<meta property=\"og:site_name\" content=\"ODYSSEUS II\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/\",\"name\":\"Indsendte bidrag - ODYSSEUS II\",\"isPartOf\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\"},\"datePublished\":\"2015-06-18T18:03:07+00:00\",\"dateModified\":\"2015-06-18T18:03:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/#breadcrumb\"},\"inLanguage\":\"da-DK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/da\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opdagelsesrejsende\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Indsendte bidrag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/de\/\",\"name\":\"ODYSSEUS II\",\"description\":\"Europ\u00e6isk Rumkonkurrence for Unger\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"da-DK\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indsendte bidrag - ODYSSEUS II","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/","og_locale":"da_DK","og_type":"article","og_title":"Indsendte bidrag - ODYSSEUS II","og_description":"Alle bidrag bliver vist p\u00e5 Odysseus-hjemmesiden efter udl\u00f8b af frist for indsendelse af bidrag (januar 2016).","og_url":"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/","og_site_name":"ODYSSEUS II","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/","url":"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/","name":"Indsendte bidrag - ODYSSEUS II","isPartOf":{"@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website"},"datePublished":"2015-06-18T18:03:07+00:00","dateModified":"2015-06-18T18:03:07+00:00","breadcrumb":{"@id":"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/#breadcrumb"},"inLanguage":"da-DK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/indsendte-bidrag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseus-contests.eu\/2016\/da\/"},{"@type":"ListItem","position":2,"name":"Opdagelsesrejsende","item":"https:\/\/odysseus-contests.eu\/2016\/da\/opdagelsesrejsende\/"},{"@type":"ListItem","position":3,"name":"Indsendte bidrag"}]},{"@type":"WebSite","@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website","url":"https:\/\/odysseus-contests.eu\/2016\/de\/","name":"ODYSSEUS II","description":"Europ\u00e6isk Rumkonkurrence for Unger","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"da-DK"}]}},"_links":{"self":[{"href":"https:\/\/odysseus-contests.eu\/2016\/da\/wp-json\/wp\/v2\/pages\/536"}],"collection":[{"href":"https:\/\/odysseus-contests.eu\/2016\/da\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odysseus-contests.eu\/2016\/da\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/da\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/da\/wp-json\/wp\/v2\/comments?post=536"}],"version-history":[{"count":0,"href":"https:\/\/odysseus-contests.eu\/2016\/da\/wp-json\/wp\/v2\/pages\/536\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/da\/wp-json\/wp\/v2\/pages\/517"}],"wp:attachment":[{"href":"https:\/\/odysseus-contests.eu\/2016\/da\/wp-json\/wp\/v2\/media?parent=536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}