{"id":4895,"date":"2015-09-04T14:07:23","date_gmt":"2015-09-04T11:07:23","guid":{"rendered":"http:\/\/odysseus-contests.eu\/2016\/?page_id=4895"},"modified":"2015-09-04T14:07:23","modified_gmt":"2015-09-04T11:07:23","slug":"%d0%bd%d0%b0%d0%b3%d1%80%d0%b0%d0%b4%d0%b8","status":"publish","type":"page","link":"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/%d0%bd%d0%b0%d0%b3%d1%80%d0%b0%d0%b4%d0%b8\/","title":{"rendered":"\u041d\u0430\u0433\u0440\u0430\u0434\u0438"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"img-responsive alignleft wp-image-337 size-full\" src=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/content-prizes-skywalkers1.jpg\" alt=\"content-prizes-skywalkers\" width=\"700\" height=\"400\" srcset=\"https:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/content-prizes-skywalkers1.jpg 700w, https:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/content-prizes-skywalkers1-300x171.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>\u0418\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u044f\u0442\u0430 \u043d\u0430 \u0432\u0441\u0438\u0447\u043a\u0438 \u043d\u0430\u0446\u0438\u043e\u043d\u0430\u043b\u043d\u0438 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u0438 \u0438 \u043f\u043e\u0434\u0433\u043b\u0430\u0441\u043d\u0438\u0446\u0438 \u0432 \u043a\u043e\u043d\u043a\u0443\u0440\u0441\u043d\u0438\u0442\u0435 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438 Junior Skywalkers \u0438 Senior Skywalkers \u0449\u0435 \u0431\u044a\u0434\u0430\u0442 \u043f\u043e\u043a\u0430\u0437\u0430\u043d\u0438 \u0432 \u0413\u0430\u043b\u0435\u0440\u0438\u044f\u0442\u0430 \u043d\u0430 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u0438\u0442\u0435. \u0421\u044a\u0449\u043e \u0442\u0430\u043a\u0430 \u0432\u0441\u0438\u0447\u043a\u0438 \u043d\u0430\u0446\u0438\u043e\u043d\u0430\u043b\u043d\u0438 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u0438 \u0438 \u043f\u043e\u0434\u0433\u043b\u0430\u0441\u043d\u0438\u0446\u0438 \u0432 \u0441\u044a\u0449\u0438\u0442\u0435 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438 \u0449\u0435 \u043f\u043e\u043b\u0443\u0447\u0430\u0442 \u043f\u043e \u0435\u0434\u0438\u043d \u043c\u0435\u0434\u0430\u043b \u043d\u0430 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u044f \u0438 \u0435\u0434\u0438\u043d \u043a\u043e\u043c\u043f\u043b\u0435\u043a\u0442 \u0437\u0430 \u043c\u043e\u0434\u0435\u043b \u043d\u0430 \u0440\u0430\u043a\u0435\u0442\u0430, \u043a\u043e\u0438\u0442\u043e \u0449\u0435 \u0431\u044a\u0434\u0430\u0442 \u0438\u0437\u043f\u0440\u0430\u0442\u0435\u043d\u0438 \u043e\u0442 \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0430\u0442\u043e\u0440\u0438\u0442\u0435 \u0434\u0438\u0440\u0435\u043a\u0442\u043d\u043e \u0434\u043e \u0442\u044f\u0445\u043d\u043e\u0442\u043e \u0443\u0447\u0438\u043b\u0438\u0449\u0435 \u0438\u043b\u0438 \u0434\u043e\u043c.<\/p>\n<p>\u041f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u0438\u0442\u0435 \u0432 \u043a\u043e\u043d\u043a\u0443\u0440\u0441\u0430 \u0437\u0430 \u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435 Skywalkers, \u0438\u0437\u0431\u0440\u0430\u043d\u0438 \u043d\u0430 \u041c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0438\u044f \u0444\u0438\u043d\u0430\u043b, \u0449\u0435 \u043f\u043e\u043b\u0443\u0447\u0430\u0442 \u043f\u043e \u0435\u0434\u0438\u043d iPad Air 2 \u0441 e-books \u0438 \u043f\u0440\u0438\u043b\u043e\u0436\u0435\u043d\u0438\u044f, \u0441\u0432\u044a\u0440\u0437\u0430\u043d\u0438 \u0441 \u043a\u043e\u0441\u043c\u043e\u0441\u0430, \u0438 \u0434\u0438\u043f\u043b\u043e\u043c \u201eEuropean Youth Space Ambassador\u201d, \u043a\u043e\u0438\u0442\u043e \u0449\u0435 \u0431\u044a\u0434\u0430\u0442 \u0438\u0437\u043f\u0440\u0430\u0442\u0435\u043d\u0438 \u0434\u0438\u0440\u0435\u043a\u0442\u043d\u043e \u0434\u043e \u0442\u044f\u0445\u043d\u043e\u0442\u043e \u0443\u0447\u0438\u043b\u0438\u0449\u0435 \u0438\u043b\u0438 \u0434\u043e\u043c.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u0418\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u044f\u0442\u0430 \u043d\u0430 \u0432\u0441\u0438\u0447\u043a\u0438 \u043d\u0430\u0446\u0438\u043e\u043d\u0430\u043b\u043d\u0438 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u0438 \u0438 \u043f\u043e\u0434\u0433\u043b\u0430\u0441\u043d\u0438\u0446\u0438 \u0432 \u043a\u043e\u043d\u043a\u0443\u0440\u0441\u043d\u0438\u0442\u0435 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438 Junior Skywalkers \u0438 Senior Skywalkers \u0449\u0435 \u0431\u044a\u0434\u0430\u0442 \u043f\u043e\u043a\u0430\u0437\u0430\u043d\u0438 \u0432 \u0413\u0430\u043b\u0435\u0440\u0438\u044f\u0442\u0430 \u043d\u0430 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u0438\u0442\u0435. \u0421\u044a\u0449\u043e \u0442\u0430\u043a\u0430 \u0432\u0441\u0438\u0447\u043a\u0438 \u043d\u0430\u0446\u0438\u043e\u043d\u0430\u043b\u043d\u0438 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u0438 \u0438 \u043f\u043e\u0434\u0433\u043b\u0430\u0441\u043d\u0438\u0446\u0438 \u0432 \u0441\u044a\u0449\u0438\u0442\u0435 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438 \u0449\u0435 \u043f\u043e\u043b\u0443\u0447\u0430\u0442 \u043f\u043e \u0435\u0434\u0438\u043d \u043c\u0435\u0434\u0430\u043b \u043d\u0430 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u044f \u0438 \u0435\u0434\u0438\u043d \u043a\u043e\u043c\u043f\u043b\u0435\u043a\u0442 \u0437\u0430 \u043c\u043e\u0434\u0435\u043b \u043d\u0430 \u0440\u0430\u043a\u0435\u0442\u0430, \u043a\u043e\u0438\u0442\u043e \u0449\u0435 \u0431\u044a\u0434\u0430\u0442 \u0438\u0437\u043f\u0440\u0430\u0442\u0435\u043d\u0438 \u043e\u0442 \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0430\u0442\u043e\u0440\u0438\u0442\u0435 \u0434\u0438\u0440\u0435\u043a\u0442\u043d\u043e \u0434\u043e [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":4742,"menu_order":40,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u041d\u0430\u0433\u0440\u0430\u0434\u0438 - ODYSSEUS II<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/\u043d\u0430\u0433\u0440\u0430\u0434\u0438\/\" \/>\n<meta property=\"og:locale\" content=\"bg_BG\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u041d\u0430\u0433\u0440\u0430\u0434\u0438 - ODYSSEUS II\" \/>\n<meta property=\"og:description\" content=\"&nbsp; \u0418\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u044f\u0442\u0430 \u043d\u0430 \u0432\u0441\u0438\u0447\u043a\u0438 \u043d\u0430\u0446\u0438\u043e\u043d\u0430\u043b\u043d\u0438 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u0438 \u0438 \u043f\u043e\u0434\u0433\u043b\u0430\u0441\u043d\u0438\u0446\u0438 \u0432 \u043a\u043e\u043d\u043a\u0443\u0440\u0441\u043d\u0438\u0442\u0435 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438 Junior Skywalkers \u0438 Senior Skywalkers \u0449\u0435 \u0431\u044a\u0434\u0430\u0442 \u043f\u043e\u043a\u0430\u0437\u0430\u043d\u0438 \u0432 \u0413\u0430\u043b\u0435\u0440\u0438\u044f\u0442\u0430 \u043d\u0430 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u0438\u0442\u0435. \u0421\u044a\u0449\u043e \u0442\u0430\u043a\u0430 \u0432\u0441\u0438\u0447\u043a\u0438 \u043d\u0430\u0446\u0438\u043e\u043d\u0430\u043b\u043d\u0438 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u0438 \u0438 \u043f\u043e\u0434\u0433\u043b\u0430\u0441\u043d\u0438\u0446\u0438 \u0432 \u0441\u044a\u0449\u0438\u0442\u0435 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438 \u0449\u0435 \u043f\u043e\u043b\u0443\u0447\u0430\u0442 \u043f\u043e \u0435\u0434\u0438\u043d \u043c\u0435\u0434\u0430\u043b \u043d\u0430 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u044f \u0438 \u0435\u0434\u0438\u043d \u043a\u043e\u043c\u043f\u043b\u0435\u043a\u0442 \u0437\u0430 \u043c\u043e\u0434\u0435\u043b \u043d\u0430 \u0440\u0430\u043a\u0435\u0442\u0430, \u043a\u043e\u0438\u0442\u043e \u0449\u0435 \u0431\u044a\u0434\u0430\u0442 \u0438\u0437\u043f\u0440\u0430\u0442\u0435\u043d\u0438 \u043e\u0442 \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0430\u0442\u043e\u0440\u0438\u0442\u0435 \u0434\u0438\u0440\u0435\u043a\u0442\u043d\u043e \u0434\u043e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/\u043d\u0430\u0433\u0440\u0430\u0434\u0438\/\" \/>\n<meta property=\"og:site_name\" content=\"ODYSSEUS II\" \/>\n<meta property=\"og:image\" content=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/content-prizes-skywalkers1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/%d0%bd%d0%b0%d0%b3%d1%80%d0%b0%d0%b4%d0%b8\/\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/%d0%bd%d0%b0%d0%b3%d1%80%d0%b0%d0%b4%d0%b8\/\",\"name\":\"\u041d\u0430\u0433\u0440\u0430\u0434\u0438 - ODYSSEUS II\",\"isPartOf\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\"},\"datePublished\":\"2015-09-04T11:07:23+00:00\",\"dateModified\":\"2015-09-04T11:07:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/%d0%bd%d0%b0%d0%b3%d1%80%d0%b0%d0%b4%d0%b8\/#breadcrumb\"},\"inLanguage\":\"bg-BG\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/%d0%bd%d0%b0%d0%b3%d1%80%d0%b0%d0%b4%d0%b8\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/%d0%bd%d0%b0%d0%b3%d1%80%d0%b0%d0%b4%d0%b8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Skywalkers\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u041d\u0430\u0433\u0440\u0430\u0434\u0438\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/de\/\",\"name\":\"ODYSSEUS II\",\"description\":\"\u0415\u0432\u0440\u043e\u043f\u0435\u0439\u0441\u043a\u0438 \u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0438 \u043a\u043e\u043d\u043a\u0443\u0440\u0441 \u0437\u0430 \u043c\u043b\u0430\u0434\u0435\u0436\u0438\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"bg-BG\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041d\u0430\u0433\u0440\u0430\u0434\u0438 - ODYSSEUS II","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/\u043d\u0430\u0433\u0440\u0430\u0434\u0438\/","og_locale":"bg_BG","og_type":"article","og_title":"\u041d\u0430\u0433\u0440\u0430\u0434\u0438 - ODYSSEUS II","og_description":"&nbsp; \u0418\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u044f\u0442\u0430 \u043d\u0430 \u0432\u0441\u0438\u0447\u043a\u0438 \u043d\u0430\u0446\u0438\u043e\u043d\u0430\u043b\u043d\u0438 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u0438 \u0438 \u043f\u043e\u0434\u0433\u043b\u0430\u0441\u043d\u0438\u0446\u0438 \u0432 \u043a\u043e\u043d\u043a\u0443\u0440\u0441\u043d\u0438\u0442\u0435 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438 Junior Skywalkers \u0438 Senior Skywalkers \u0449\u0435 \u0431\u044a\u0434\u0430\u0442 \u043f\u043e\u043a\u0430\u0437\u0430\u043d\u0438 \u0432 \u0413\u0430\u043b\u0435\u0440\u0438\u044f\u0442\u0430 \u043d\u0430 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u0438\u0442\u0435. \u0421\u044a\u0449\u043e \u0442\u0430\u043a\u0430 \u0432\u0441\u0438\u0447\u043a\u0438 \u043d\u0430\u0446\u0438\u043e\u043d\u0430\u043b\u043d\u0438 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u0438 \u0438 \u043f\u043e\u0434\u0433\u043b\u0430\u0441\u043d\u0438\u0446\u0438 \u0432 \u0441\u044a\u0449\u0438\u0442\u0435 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438 \u0449\u0435 \u043f\u043e\u043b\u0443\u0447\u0430\u0442 \u043f\u043e \u0435\u0434\u0438\u043d \u043c\u0435\u0434\u0430\u043b \u043d\u0430 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b\u044f \u0438 \u0435\u0434\u0438\u043d \u043a\u043e\u043c\u043f\u043b\u0435\u043a\u0442 \u0437\u0430 \u043c\u043e\u0434\u0435\u043b \u043d\u0430 \u0440\u0430\u043a\u0435\u0442\u0430, \u043a\u043e\u0438\u0442\u043e \u0449\u0435 \u0431\u044a\u0434\u0430\u0442 \u0438\u0437\u043f\u0440\u0430\u0442\u0435\u043d\u0438 \u043e\u0442 \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0430\u0442\u043e\u0440\u0438\u0442\u0435 \u0434\u0438\u0440\u0435\u043a\u0442\u043d\u043e \u0434\u043e [&hellip;]","og_url":"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/\u043d\u0430\u0433\u0440\u0430\u0434\u0438\/","og_site_name":"ODYSSEUS II","og_image":[{"url":"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/content-prizes-skywalkers1.jpg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/%d0%bd%d0%b0%d0%b3%d1%80%d0%b0%d0%b4%d0%b8\/","url":"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/%d0%bd%d0%b0%d0%b3%d1%80%d0%b0%d0%b4%d0%b8\/","name":"\u041d\u0430\u0433\u0440\u0430\u0434\u0438 - ODYSSEUS II","isPartOf":{"@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website"},"datePublished":"2015-09-04T11:07:23+00:00","dateModified":"2015-09-04T11:07:23+00:00","breadcrumb":{"@id":"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/%d0%bd%d0%b0%d0%b3%d1%80%d0%b0%d0%b4%d0%b8\/#breadcrumb"},"inLanguage":"bg-BG","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/%d0%bd%d0%b0%d0%b3%d1%80%d0%b0%d0%b4%d0%b8\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/%d0%bd%d0%b0%d0%b3%d1%80%d0%b0%d0%b4%d0%b8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseus-contests.eu\/2016\/bg\/"},{"@type":"ListItem","position":2,"name":"Skywalkers","item":"https:\/\/odysseus-contests.eu\/2016\/bg\/skywalkers\/"},{"@type":"ListItem","position":3,"name":"\u041d\u0430\u0433\u0440\u0430\u0434\u0438"}]},{"@type":"WebSite","@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website","url":"https:\/\/odysseus-contests.eu\/2016\/de\/","name":"ODYSSEUS II","description":"\u0415\u0432\u0440\u043e\u043f\u0435\u0439\u0441\u043a\u0438 \u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0438 \u043a\u043e\u043d\u043a\u0443\u0440\u0441 \u0437\u0430 \u043c\u043b\u0430\u0434\u0435\u0436\u0438","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"bg-BG"}]}},"_links":{"self":[{"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/pages\/4895"}],"collection":[{"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/comments?post=4895"}],"version-history":[{"count":0,"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/pages\/4895\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/pages\/4742"}],"wp:attachment":[{"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/media?parent=4895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}