{"id":4846,"date":"2015-09-04T13:15:05","date_gmt":"2015-09-04T10:15:05","guid":{"rendered":"http:\/\/odysseus-contests.eu\/2016\/?page_id=4846"},"modified":"2015-09-04T13:15:05","modified_gmt":"2015-09-04T10:15:05","slug":"%d0%b8%d0%b7%d1%82%d0%be%d1%87%d0%bd%d0%b8%d1%86%d0%b8","status":"publish","type":"page","link":"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/%d0%b8%d0%b7%d1%82%d0%be%d1%87%d0%bd%d0%b8%d1%86%d0%b8\/","title":{"rendered":"\u0418\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438"},"content":{"rendered":"<p><strong>\u0421\u043b\u044a\u043d\u0447\u0435\u0432\u0430\u0442\u0430 \u0441\u0438\u0441\u0442\u0435\u043c\u0430 \u0438<\/strong> <strong>\u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0430\u0442\u0430 \u043d\u0430\u0443\u043a\u0430<\/strong><\/p>\n<p><em>\u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e<\/em><\/p>\n<p><strong>\u00a0<\/strong><strong>\u0415\u0432\u0440\u043e\u043f\u0430<\/strong> <strong>\u0432 \u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0438 \u043c\u0438\u0441\u0438\u0438<\/strong><\/p>\n<p><em>\u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e<\/em><\/p>\n<p><strong>\u00a0<\/strong><strong>\u0427\u043e\u0432\u0435\u0448\u043a\u0438 \u0441\u044a\u0449\u0435\u0441\u0442\u0432\u0430<\/strong> <strong>\u043d\u0430 \u041c\u0430\u0440\u0441<\/strong><\/p>\n<p><em>\u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e<\/em><\/p>\n<p><strong>\u00a0<\/strong><strong>\u0410\u0441\u0442\u0440\u043e\u0431\u0438\u043e\u043b\u043e\u0433\u0438\u044f \u2013 \u0422\u044a\u0440\u0441\u0435\u043d\u0435 \u043d\u0430 \u0436\u0438\u0432\u043e\u0442 \u0432\u044a\u0432 \u0412\u0441\u0435\u043b\u0435\u043d\u0430\u0442\u0430<\/strong><\/p>\n<p><em>\u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0421\u043b\u044a\u043d\u0447\u0435\u0432\u0430\u0442\u0430 \u0441\u0438\u0441\u0442\u0435\u043c\u0430 \u0438 \u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0430\u0442\u0430 \u043d\u0430\u0443\u043a\u0430 \u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e \u00a0\u0415\u0432\u0440\u043e\u043f\u0430 \u0432 \u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0438 \u043c\u0438\u0441\u0438\u0438 \u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e \u00a0\u0427\u043e\u0432\u0435\u0448\u043a\u0438 \u0441\u044a\u0449\u0435\u0441\u0442\u0432\u0430 \u043d\u0430 \u041c\u0430\u0440\u0441 \u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e \u00a0\u0410\u0441\u0442\u0440\u043e\u0431\u0438\u043e\u043b\u043e\u0433\u0438\u044f \u2013 \u0422\u044a\u0440\u0441\u0435\u043d\u0435 \u043d\u0430 \u0436\u0438\u0432\u043e\u0442 \u0432\u044a\u0432 \u0412\u0441\u0435\u043b\u0435\u043d\u0430\u0442\u0430 \u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":4750,"menu_order":70,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0418\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438 - ODYSSEUS II<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/\u0438\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438\/\" \/>\n<meta property=\"og:locale\" content=\"bg_BG\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0418\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438 - ODYSSEUS II\" \/>\n<meta property=\"og:description\" content=\"\u0421\u043b\u044a\u043d\u0447\u0435\u0432\u0430\u0442\u0430 \u0441\u0438\u0441\u0442\u0435\u043c\u0430 \u0438 \u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0430\u0442\u0430 \u043d\u0430\u0443\u043a\u0430 \u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e \u00a0\u0415\u0432\u0440\u043e\u043f\u0430 \u0432 \u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0438 \u043c\u0438\u0441\u0438\u0438 \u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e \u00a0\u0427\u043e\u0432\u0435\u0448\u043a\u0438 \u0441\u044a\u0449\u0435\u0441\u0442\u0432\u0430 \u043d\u0430 \u041c\u0430\u0440\u0441 \u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e \u00a0\u0410\u0441\u0442\u0440\u043e\u0431\u0438\u043e\u043b\u043e\u0433\u0438\u044f \u2013 \u0422\u044a\u0440\u0441\u0435\u043d\u0435 \u043d\u0430 \u0436\u0438\u0432\u043e\u0442 \u0432\u044a\u0432 \u0412\u0441\u0435\u043b\u0435\u043d\u0430\u0442\u0430 \u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/\u0438\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438\/\" \/>\n<meta property=\"og:site_name\" content=\"ODYSSEUS II\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/%d0%b8%d0%b7%d1%82%d0%be%d1%87%d0%bd%d0%b8%d1%86%d0%b8\/\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/%d0%b8%d0%b7%d1%82%d0%be%d1%87%d0%bd%d0%b8%d1%86%d0%b8\/\",\"name\":\"\u0418\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438 - ODYSSEUS II\",\"isPartOf\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\"},\"datePublished\":\"2015-09-04T10:15:05+00:00\",\"dateModified\":\"2015-09-04T10:15:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/%d0%b8%d0%b7%d1%82%d0%be%d1%87%d0%bd%d0%b8%d1%86%d0%b8\/#breadcrumb\"},\"inLanguage\":\"bg-BG\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/%d0%b8%d0%b7%d1%82%d0%be%d1%87%d0%bd%d0%b8%d1%86%d0%b8\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/%d0%b8%d0%b7%d1%82%d0%be%d1%87%d0%bd%d0%b8%d1%86%d0%b8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pioneers\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0418\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/de\/\",\"name\":\"ODYSSEUS II\",\"description\":\"\u0415\u0432\u0440\u043e\u043f\u0435\u0439\u0441\u043a\u0438 \u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0438 \u043a\u043e\u043d\u043a\u0443\u0440\u0441 \u0437\u0430 \u043c\u043b\u0430\u0434\u0435\u0436\u0438\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"bg-BG\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0418\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438 - ODYSSEUS II","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/\u0438\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438\/","og_locale":"bg_BG","og_type":"article","og_title":"\u0418\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438 - ODYSSEUS II","og_description":"\u0421\u043b\u044a\u043d\u0447\u0435\u0432\u0430\u0442\u0430 \u0441\u0438\u0441\u0442\u0435\u043c\u0430 \u0438 \u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0430\u0442\u0430 \u043d\u0430\u0443\u043a\u0430 \u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e \u00a0\u0415\u0432\u0440\u043e\u043f\u0430 \u0432 \u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0438 \u043c\u0438\u0441\u0438\u0438 \u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e \u00a0\u0427\u043e\u0432\u0435\u0448\u043a\u0438 \u0441\u044a\u0449\u0435\u0441\u0442\u0432\u0430 \u043d\u0430 \u041c\u0430\u0440\u0441 \u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e \u00a0\u0410\u0441\u0442\u0440\u043e\u0431\u0438\u043e\u043b\u043e\u0433\u0438\u044f \u2013 \u0422\u044a\u0440\u0441\u0435\u043d\u0435 \u043d\u0430 \u0436\u0438\u0432\u043e\u0442 \u0432\u044a\u0432 \u0412\u0441\u0435\u043b\u0435\u043d\u0430\u0442\u0430 \u041e\u0447\u0430\u043a\u0432\u0430\u0439\u0442\u0435 \u0441\u043a\u043e\u0440\u043e","og_url":"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/\u0438\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438\/","og_site_name":"ODYSSEUS II","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/%d0%b8%d0%b7%d1%82%d0%be%d1%87%d0%bd%d0%b8%d1%86%d0%b8\/","url":"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/%d0%b8%d0%b7%d1%82%d0%be%d1%87%d0%bd%d0%b8%d1%86%d0%b8\/","name":"\u0418\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438 - ODYSSEUS II","isPartOf":{"@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website"},"datePublished":"2015-09-04T10:15:05+00:00","dateModified":"2015-09-04T10:15:05+00:00","breadcrumb":{"@id":"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/%d0%b8%d0%b7%d1%82%d0%be%d1%87%d0%bd%d0%b8%d1%86%d0%b8\/#breadcrumb"},"inLanguage":"bg-BG","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/%d0%b8%d0%b7%d1%82%d0%be%d1%87%d0%bd%d0%b8%d1%86%d0%b8\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/%d0%b8%d0%b7%d1%82%d0%be%d1%87%d0%bd%d0%b8%d1%86%d0%b8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseus-contests.eu\/2016\/bg\/"},{"@type":"ListItem","position":2,"name":"Pioneers","item":"https:\/\/odysseus-contests.eu\/2016\/bg\/pioneers-6\/"},{"@type":"ListItem","position":3,"name":"\u0418\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438"}]},{"@type":"WebSite","@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website","url":"https:\/\/odysseus-contests.eu\/2016\/de\/","name":"ODYSSEUS II","description":"\u0415\u0432\u0440\u043e\u043f\u0435\u0439\u0441\u043a\u0438 \u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0438 \u043a\u043e\u043d\u043a\u0443\u0440\u0441 \u0437\u0430 \u043c\u043b\u0430\u0434\u0435\u0436\u0438","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"bg-BG"}]}},"_links":{"self":[{"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/pages\/4846"}],"collection":[{"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/comments?post=4846"}],"version-history":[{"count":0,"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/pages\/4846\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/pages\/4750"}],"wp:attachment":[{"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/media?parent=4846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}