{"id":4810,"date":"2015-09-04T00:36:33","date_gmt":"2015-09-03T21:36:33","guid":{"rendered":"http:\/\/odysseus-contests.eu\/2016\/?page_id=4810"},"modified":"2015-09-09T01:46:21","modified_gmt":"2015-09-08T22:46:21","slug":"media-resources","status":"publish","type":"page","link":"https:\/\/odysseus-contests.eu\/2016\/bg\/%d0%bc%d0%b5%d0%b4%d0%b8%d0%b8\/media-resources\/","title":{"rendered":"\u041c\u0435\u0434\u0438\u0439\u043d\u0438 \u0438\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438"},"content":{"rendered":"<h3>Odysseus II Logos<\/h3>\n<p>Click <strong><a href=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/odysseus_logos.zip\">here<\/a><\/strong> to download the Odysseus II Logo in *.jpg and *.eps format.<\/p>\n<h3>Odysseus II Trailer<\/h3>\n<p><em>Teaser Video 720p\u00a0\u00a0 <\/em><a href=\"http:\/\/odysseus-contests.eu\/2016\/wp-content\/uploads\/2015\/05\/odysseus_720p.mp4\">odysseus_720p<\/a><\/p>\n<h3>Odysseus II Leaflet (EN)<\/h3>\n<p><a href=\"http:\/\/iframewidth=650height=470src=\/\/e.issuu.com\/embed.html#16787370\/15293599frameborder=0allowfullscreen\/iframe\"><iframe loading=\"lazy\" src=\"\/\/e.issuu.com\/embed.html#16787370\/15293599\" width=\"650\" height=\"470\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Odysseus II Logos Click here to download the Odysseus II Logo in *.jpg and *.eps format. Odysseus II Trailer Teaser Video 720p\u00a0\u00a0 odysseus_720p Odysseus II Leaflet (EN)<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":4807,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u041c\u0435\u0434\u0438\u0439\u043d\u0438 \u0438\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438 - ODYSSEUS II<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseus-contests.eu\/2016\/bg\/\u043c\u0435\u0434\u0438\u0438\/media-resources\/\" \/>\n<meta property=\"og:locale\" content=\"bg_BG\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u041c\u0435\u0434\u0438\u0439\u043d\u0438 \u0438\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438 - ODYSSEUS II\" \/>\n<meta property=\"og:description\" content=\"Odysseus II Logos Click here to download the Odysseus II Logo in *.jpg and *.eps format. Odysseus II Trailer Teaser Video 720p\u00a0\u00a0 odysseus_720p Odysseus II Leaflet (EN)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseus-contests.eu\/2016\/bg\/\u043c\u0435\u0434\u0438\u0438\/media-resources\/\" \/>\n<meta property=\"og:site_name\" content=\"ODYSSEUS II\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-08T22:46:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/%d0%bc%d0%b5%d0%b4%d0%b8%d0%b8\/media-resources\/\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/%d0%bc%d0%b5%d0%b4%d0%b8%d0%b8\/media-resources\/\",\"name\":\"\u041c\u0435\u0434\u0438\u0439\u043d\u0438 \u0438\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438 - ODYSSEUS II\",\"isPartOf\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\"},\"datePublished\":\"2015-09-03T21:36:33+00:00\",\"dateModified\":\"2015-09-08T22:46:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/%d0%bc%d0%b5%d0%b4%d0%b8%d0%b8\/media-resources\/#breadcrumb\"},\"inLanguage\":\"bg-BG\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odysseus-contests.eu\/2016\/bg\/%d0%bc%d0%b5%d0%b4%d0%b8%d0%b8\/media-resources\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/%d0%bc%d0%b5%d0%b4%d0%b8%d0%b8\/media-resources\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041c\u0435\u0434\u0438\u0438\",\"item\":\"https:\/\/odysseus-contests.eu\/2016\/bg\/%d0%bc%d0%b5%d0%b4%d0%b8%d0%b8\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u041c\u0435\u0434\u0438\u0439\u043d\u0438 \u0438\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odysseus-contests.eu\/2016\/de\/#website\",\"url\":\"https:\/\/odysseus-contests.eu\/2016\/de\/\",\"name\":\"ODYSSEUS II\",\"description\":\"\u0415\u0432\u0440\u043e\u043f\u0435\u0439\u0441\u043a\u0438 \u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0438 \u043a\u043e\u043d\u043a\u0443\u0440\u0441 \u0437\u0430 \u043c\u043b\u0430\u0434\u0435\u0436\u0438\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"bg-BG\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041c\u0435\u0434\u0438\u0439\u043d\u0438 \u0438\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438 - ODYSSEUS II","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseus-contests.eu\/2016\/bg\/\u043c\u0435\u0434\u0438\u0438\/media-resources\/","og_locale":"bg_BG","og_type":"article","og_title":"\u041c\u0435\u0434\u0438\u0439\u043d\u0438 \u0438\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438 - ODYSSEUS II","og_description":"Odysseus II Logos Click here to download the Odysseus II Logo in *.jpg and *.eps format. Odysseus II Trailer Teaser Video 720p\u00a0\u00a0 odysseus_720p Odysseus II Leaflet (EN)","og_url":"https:\/\/odysseus-contests.eu\/2016\/bg\/\u043c\u0435\u0434\u0438\u0438\/media-resources\/","og_site_name":"ODYSSEUS II","article_modified_time":"2015-09-08T22:46:21+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseus-contests.eu\/2016\/bg\/%d0%bc%d0%b5%d0%b4%d0%b8%d0%b8\/media-resources\/","url":"https:\/\/odysseus-contests.eu\/2016\/bg\/%d0%bc%d0%b5%d0%b4%d0%b8%d0%b8\/media-resources\/","name":"\u041c\u0435\u0434\u0438\u0439\u043d\u0438 \u0438\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438 - ODYSSEUS II","isPartOf":{"@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website"},"datePublished":"2015-09-03T21:36:33+00:00","dateModified":"2015-09-08T22:46:21+00:00","breadcrumb":{"@id":"https:\/\/odysseus-contests.eu\/2016\/bg\/%d0%bc%d0%b5%d0%b4%d0%b8%d0%b8\/media-resources\/#breadcrumb"},"inLanguage":"bg-BG","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseus-contests.eu\/2016\/bg\/%d0%bc%d0%b5%d0%b4%d0%b8%d0%b8\/media-resources\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/odysseus-contests.eu\/2016\/bg\/%d0%bc%d0%b5%d0%b4%d0%b8%d0%b8\/media-resources\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseus-contests.eu\/2016\/bg\/"},{"@type":"ListItem","position":2,"name":"\u041c\u0435\u0434\u0438\u0438","item":"https:\/\/odysseus-contests.eu\/2016\/bg\/%d0%bc%d0%b5%d0%b4%d0%b8%d0%b8\/"},{"@type":"ListItem","position":3,"name":"\u041c\u0435\u0434\u0438\u0439\u043d\u0438 \u0438\u0437\u0442\u043e\u0447\u043d\u0438\u0446\u0438"}]},{"@type":"WebSite","@id":"https:\/\/odysseus-contests.eu\/2016\/de\/#website","url":"https:\/\/odysseus-contests.eu\/2016\/de\/","name":"ODYSSEUS II","description":"\u0415\u0432\u0440\u043e\u043f\u0435\u0439\u0441\u043a\u0438 \u043a\u043e\u0441\u043c\u0438\u0447\u0435\u0441\u043a\u0438 \u043a\u043e\u043d\u043a\u0443\u0440\u0441 \u0437\u0430 \u043c\u043b\u0430\u0434\u0435\u0436\u0438","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseus-contests.eu\/2016\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"bg-BG"}]}},"_links":{"self":[{"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/pages\/4810"}],"collection":[{"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/comments?post=4810"}],"version-history":[{"count":0,"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/pages\/4810\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/pages\/4807"}],"wp:attachment":[{"href":"https:\/\/odysseus-contests.eu\/2016\/bg\/wp-json\/wp\/v2\/media?parent=4810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}